{"id":7590,"date":"2025-10-18T09:28:10","date_gmt":"2025-10-18T07:28:10","guid":{"rendered":"https:\/\/linn-pumpen.de\/?post_type=portfolio&#038;p=7590"},"modified":"2025-11-20T10:27:38","modified_gmt":"2025-11-20T09:27:38","slug":"ap-2","status":"publish","type":"portfolio","link":"https:\/\/linn-pumpen.de\/en\/produkt\/ap-2\/","title":{"rendered":"VP"},"content":{"rendered":"<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2f21y8g-a69b7328abd1fe86310bed170d78b9b3\">\n.av-tab-section-outer-container.av-2f21y8g-a69b7328abd1fe86310bed170d78b9b3 .av-tab-section-tab-title-container{\nbackground-color:#f2f4f6;\n}\n#top .av-tab-section-outer-container.av-2f21y8g-a69b7328abd1fe86310bed170d78b9b3 .av-section-tab-title{\ncolor:#1a1a1a;\n}\n#top .av-tab-section-outer-container.av-2f21y8g-a69b7328abd1fe86310bed170d78b9b3 .av-active-tab-title.av-section-tab-title{\ncolor:#0069b4;\n}\n#top .av-tab-section-outer-container.av-2f21y8g-a69b7328abd1fe86310bed170d78b9b3 .av-section-tab-title:hover{\ncolor:#0069b4;\n}\n#top .av-tab-section-outer-container.av-2f21y8g-a69b7328abd1fe86310bed170d78b9b3 .av-active-tab-title.av-section-tab-title:hover{\ncolor:#0069b4;\n}\n<\/style>\n<div id='av-tab-section-1'  class='av-tab-section-container entry-content-wrapper main_color av-tab-no-transition av-tab-content-auto  av-tab-above-content  avia-builder-el-0  el_before_av_section  avia-builder-el-first  container_wrap sidebar_right'  ><div class='av-tab-section-outer-container av-2f21y8g-a69b7328abd1fe86310bed170d78b9b3'><div class='av-tab-section-tab-title-container avia-tab-title-padding-small av-custom-tab-color' role='tablist'><a href='#av-tab-section-1-1-link' data-av-tab-section-title='1' class='av-section-tab-title av-active-tab-title no-scroll av-2d3knn4-dc9c7b4b9400e182f91e07ede43b7030 av-tab-with-icon av-tab-no-image' role='tab' tabindex='0' aria-controls='av-tab-section-1-1'><span class='av-tab-section-icon avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue84c' data-av_iconfont='entypo-fontello' ><\/span><span class='av-outer-tab-title'><span class='av-inner-tab-title'>Overview<\/span><\/span><span class=\"av-tab-arrow-container\"><span><\/span><\/span><\/a><a href='#downloads' data-av-tab-section-title='2' class='av-section-tab-title  av-3rhcjk-c49f2bdaac61448ec7024bad9055e9a9 av-tab-with-icon av-tab-no-image' role='tab' tabindex='0' aria-controls='av-tab-section-1-2'><span class='av-tab-section-icon avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue82d' data-av_iconfont='entypo-fontello' ><\/span><span class='av-outer-tab-title'><span class='av-inner-tab-title'>Downloads<\/span><\/span><span class=\"av-tab-arrow-container\"><span><\/span><\/span><\/a><\/div><div class='avia-slideshow-arrows av-tabsection-arrow' ><a href='#prev' class='prev-slide av_prev_tab_section av-tab-section-slide avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Previous\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewbox=\"0 0 15 32\" preserveaspectratio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Previous<\/title>\n<desc id='av-svg-desc-1'>Previous<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Previous<\/span><\/a><a href='#next' class='next-slide av_next_tab_section av-tab-section-slide avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Next\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewbox=\"0 0 15 32\" preserveaspectratio=\"xMidYMid meet\" aria-labelledby='av-svg-title-2' aria-describedby='av-svg-desc-2' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-2'>Next<\/title>\n<desc id='av-svg-desc-2'>Next<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Next<\/span><\/a><\/div><div class='av-tab-section-inner-container avia-section-small' style='width:200vw; left:0%;'><span class=\"av_prev_tab_section av_tab_navigation\"><\/span><span class=\"av_next_tab_section av_tab_navigation\"><\/span>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2d3knn4-dc9c7b4b9400e182f91e07ede43b7030\">\n.av-layout-tab.av-2d3knn4-dc9c7b4b9400e182f91e07ede43b7030{\nvertical-align:top;\n}\n<\/style>\n<div id='av-tab-section-1-1' class='av-layout-tab av-2d3knn4-dc9c7b4b9400e182f91e07ede43b7030 av-animation-delay-container  avia-builder-el-1  el_before_av_tab_sub_section  avia-builder-el-first  lp-tabs av-active-tab-content __av_init_open' data-av-deeplink-tabs=\"uebersicht\" data-av-tab-section-content=\"1\" data-tab-section-id=\"av-tab-section-1-1\"><div class=\"av-layout-tab-inner\"><div class=\"container\"><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mgvw3vi1-8967e40507370749bcc1140308f86a20\">\n#top .av-special-heading.av-mgvw3vi1-8967e40507370749bcc1140308f86a20{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-mgvw3vi1-8967e40507370749bcc1140308f86a20 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-mgvw3vi1-8967e40507370749bcc1140308f86a20 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-mgvw3vi1-8967e40507370749bcc1140308f86a20 av-special-heading-h1  avia-builder-el-2  el_before_av_three_fifth  avia-builder-el-first'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >VP Vertical immersion pumps with peripheral impeller<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div class='flex_column_table av-2br1tu8-b73d0d21d463620fa1e89c0fc5590dab sc-av_three_fifth av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2br1tu8-b73d0d21d463620fa1e89c0fc5590dab\">\n.flex_column.av-2br1tu8-b73d0d21d463620fa1e89c0fc5590dab{\nwidth:58%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-2br1tu8-b73d0d21d463620fa1e89c0fc5590dab .av-flex-placeholder{\nwidth:5%;\n}\n<\/style>\n<div  class='flex_column av-2br1tu8-b73d0d21d463620fa1e89c0fc5590dab av_three_fifth  avia-builder-el-3  el_after_av_heading  el_before_av_two_fifth  first flex_column_table_cell av-equal-height-column av-align-top'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mgvw5n2w-4618db04d28a3c2a6506441822bcaabc\">\n#top .av_textblock_section.av-mgvw5n2w-4618db04d28a3c2a6506441822bcaabc .avia_textblock{\nfont-size:16px;\n}\n<\/style>\n<section  class='av_textblock_section av-mgvw5n2w-4618db04d28a3c2a6506441822bcaabc'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Vertical, sealless submersible pump with peripheral impeller in close-coupled design, ideal for maintaining circulation pressure in open circuit systems.<br \/>\nThese pumps ensure a high level of efficiency with low power consumption and a performance that corresponds to comparable two-stage pumps.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mgvw6hq5-c68520e1eb4b803c8fb8555b8a1148c3\">\n.avia-icon-grid-container.av-mgvw6hq5-c68520e1eb4b803c8fb8555b8a1148c3 .avia-icongrid{\njustify-content:space-between;\n}\n.avia-icon-grid-container.av-mgvw6hq5-c68520e1eb4b803c8fb8555b8a1148c3 .avia-icongrid-wrapper .icongrid_title{\nfont-size:20px;\n}\n.avia-icon-grid-container.av-mgvw6hq5-c68520e1eb4b803c8fb8555b8a1148c3 .avia-icongrid-wrapper .icongrid_subtitle{\nfont-size:20px;\ncolor:#333333;\n}\n<\/style>\n<div  class='avia-icon-grid-container av-mgvw6hq5-c68520e1eb4b803c8fb8555b8a1148c3  avia-builder-el-5  el_after_av_textblock  el_before_av_hr' ><ul id='avia-icongrid-6a047ed48ca81' class='avia-icongrid clearfix avia_animate_when_almost_visible avia-icongrid-tooltip avia-icongrid-numrow-3 avia-cell-space-between av-flex-cells av-50-break-767 av-can-break-50'>\n<li class='av-icon-cell-item av-row-with-3-cells av-row-nr-1 av-cell-1 av-first-cell-row av-first-cell-item'><div class='avia-icongrid-wrapper av-mgvw62uf-e96d76c67db8432771939942d13f3ba8'><article class='article-icon-entry av-icongrid-empty'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia-icongrid-front'><div class=\"avia-icongrid-inner\"><header class=\"entry-content-header\" aria-label=\"Icon: F\u00f6rdermenge (min\/max)\"><h4 class='av_icongrid_title icongrid_title'  itemprop=\"headline\" >Delivery rate (min\/max)<\/h4><h6 class='av_icongrid_subtitle icongrid_subtitle' ><p>0.3 \/ 4.3 m\u00b3\/h<\/p>\n<\/h6><\/header><\/div><\/div><div class='avia-icongrid-content' data-class-flipback=''><div class=\"avia-icongrid-inner\"><div class='avia-icongrid-text'  itemprop=\"text\" ><\/div><\/div><\/div><\/article><\/div><\/li>\n<li class='av-icon-cell-item av-row-with-3-cells av-row-nr-1 av-cell-2 av-first-cell-row av-inner-cell-item'><div class='avia-icongrid-wrapper av-mgvw69yu-c9414b14793c2a0b60bdb4227513e678'><article class='article-icon-entry av-icongrid-empty'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia-icongrid-front'><div class=\"avia-icongrid-inner\"><header class=\"entry-content-header\" aria-label=\"Icon: F\u00f6rderh\u00f6he (min\/max)\"><h4 class='av_icongrid_title icongrid_title'  itemprop=\"headline\" >Delivery head (min\/max)<\/h4><h6 class='av_icongrid_subtitle icongrid_subtitle' ><p>3 \/ 69 m<\/p>\n<\/h6><\/header><\/div><\/div><div class='avia-icongrid-content' data-class-flipback=''><div class=\"avia-icongrid-inner\"><div class='avia-icongrid-text'  itemprop=\"text\" ><\/div><\/div><\/div><\/article><\/div><\/li>\n<li class='av-icon-cell-item av-row-with-3-cells av-row-nr-1 av-cell-3 av-first-cell-row av-last-cell-item'><div class='avia-icongrid-wrapper av-mgvw6h96-0a15b3670f0b7c2019f7a063892f7330'><article class='article-icon-entry av-icongrid-empty'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia-icongrid-front'><div class=\"avia-icongrid-inner\"><header class=\"entry-content-header\" aria-label=\"Icon: Leistung (min\/max)\"><h4 class='av_icongrid_title icongrid_title'  itemprop=\"headline\" >Power (min\/max)<\/h4><h6 class='av_icongrid_subtitle icongrid_subtitle' ><p>0.48 \/ 1.3 kW<\/p>\n<\/h6><\/header><\/div><\/div><div class='avia-icongrid-content' data-class-flipback=''><div class=\"avia-icongrid-inner\"><div class='avia-icongrid-text'  itemprop=\"text\" ><\/div><\/div><\/div><\/article><\/div><\/li>\n<\/ul><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2a1cof4-dd6a335604a010fa666d33ccfc3310cf\">\n#top .hr.av-2a1cof4-dd6a335604a010fa666d33ccfc3310cf{\nmargin-top:5px;\nmargin-bottom:30px;\n}\n.hr.av-2a1cof4-dd6a335604a010fa666d33ccfc3310cf .hr-inner{\nwidth:45%;\nborder-color:#d7dbde;\n}\n<\/style>\n<div  class='hr av-2a1cof4-dd6a335604a010fa666d33ccfc3310cf hr-custom  avia-builder-el-6  el_after_av_icongrid  avia-builder-el-last  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><div class='av-flex-placeholder'><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-27w3oog-684862482679a09a0d9870c4f1a26c55\">\n.flex_column.av-27w3oog-684862482679a09a0d9870c4f1a26c55{\nwidth:37%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-27w3oog-684862482679a09a0d9870c4f1a26c55 .av-flex-placeholder{\nwidth:5%;\n}\n<\/style>\n<div  class='flex_column av-27w3oog-684862482679a09a0d9870c4f1a26c55 av_two_fifth  avia-builder-el-7  el_after_av_three_fifth  el_before_av_promobox  flex_column_table_cell av-equal-height-column av-align-top'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mgvw4pcm-fb6dc24b8c6c35c4e1d7b6fd17e26ef4\">\n.avia-image-container.av-mgvw4pcm-fb6dc24b8c6c35c4e1d7b6fd17e26ef4 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-mgvw4pcm-fb6dc24b8c6c35c4e1d7b6fd17e26ef4 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-mgvw4pcm-fb6dc24b8c6c35c4e1d7b6fd17e26ef4 av-styling- avia-align-center  avia-builder-el-8  avia-builder-el-no-sibling'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-7565 avia-img-lazy-loading-not-7565 avia_image' src=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png\" alt='' title='VP440'  height=\"1024\" width=\"813\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png 813w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-238x300.png 238w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-768x967.png 768w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-10x12.png 10w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-560x705.png 560w\" sizes=\"(max-width: 813px) 100vw, 813px\" \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div  class='av_promobox av-mi789d1u-2f8f38a30968147c0767ec9cc98fcf19 avia-button-yes  avia-builder-el-9  el_after_av_two_fifth  avia-builder-el-last  lp-product-cta'><div class='avia-promocontent'><\/p>\n<h3><span class=\"notion-enable-hover\" data-token-index=\"0\">Offer &amp; Design<\/span><\/h3>\n<p>Our pump experts will help you choose the right pump for your requirements.<strong data-start=\"919\" data-end=\"945\"><br \/>\n<\/strong><\/p>\n<\/div><div  class='avia-button-wrap av-mi789d1u-f406c561475b1c465c594d04847dd248-wrap avia-button-right  lp-product-cta'><a href='https:\/\/linn-pumpen.de\/en\/angebot-anfordern\/?produkt=VP Vertikale Eintauchpumpen mit Peripheralrad'  class='avia-button av-mi789d1u-f406c561475b1c465c594d04847dd248 av-link-btn avia-icon_select-no avia-size-large avia-position-right avia-color-theme-color-highlight'   aria-label=\"Request a quote\"><span class='avia_iconbox_title' >Request a quote<\/span><\/a><\/div><\/div><\/p>\n<\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3rhcjk-c49f2bdaac61448ec7024bad9055e9a9\">\n.av-layout-tab.av-3rhcjk-c49f2bdaac61448ec7024bad9055e9a9{\nvertical-align:top;\n}\n<\/style>\n<div id='av-tab-section-1-2' class='av-layout-tab av-3rhcjk-c49f2bdaac61448ec7024bad9055e9a9 av-animation-delay-container  avia-builder-el-10  el_after_av_tab_sub_section  avia-builder-el-last  lp-tabs' data-av-deeplink-tabs=\"downloads\" data-av-tab-section-content=\"2\" data-tab-section-id=\"downloads\"><div class=\"av-layout-tab-inner\"><div class=\"container\"><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2bja0g-2a533389c9a283d316a2b915e47dff0f\">\n#top .av-special-heading.av-2bja0g-2a533389c9a283d316a2b915e47dff0f{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-2bja0g-2a533389c9a283d316a2b915e47dff0f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2bja0g-2a533389c9a283d316a2b915e47dff0f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2bja0g-2a533389c9a283d316a2b915e47dff0f av-special-heading-h3  avia-builder-el-11  el_before_av_promobox  avia-builder-el-first'><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Downloads<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='av_promobox av-mgvw7i8u-87e3b9b52cef8469af155b4780088147 avia-button-yes  avia-builder-el-12  el_after_av_heading  avia-builder-el-last'><div class='avia-promocontent'><p>\nData sheet (incl. characteristic curves)<\/p>\n<\/div><div  class='avia-button-wrap av-mgvw7i8u-40a979ccea11e9687f7eb09385d8c19e-wrap avia-button-right'><a href='https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP-Eintauchpumpe-dichtungslos-de-en.pdf'  class='avia-button av-mgvw7i8u-40a979ccea11e9687f7eb09385d8c19e av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-right avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"View now\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue84c' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >View now<\/span><\/a><\/div><\/div><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9944tm-af02a2b956a6231ba299c818b66bda35\">\n.avia-section.av-9944tm-af02a2b956a6231ba299c818b66bda35{\nbackground-color:#f2f4f6;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-9944tm-af02a2b956a6231ba299c818b66bda35 alternate_color avia-section-default avia-no-border-styling  avia-builder-el-13  el_after_av_tab_section  el_before_av_one_half  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-7590'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-fu1sq2-05ec6a686aa3404125a5c85b0afd894f\">\n.flex_column.av-fu1sq2-05ec6a686aa3404125a5c85b0afd894f{\npadding:0 20px 10px 20px;\n}\n<\/style>\n<div  class='flex_column av-fu1sq2-05ec6a686aa3404125a5c85b0afd894f av_one_half  avia-builder-el-14  el_before_av_one_half  avia-builder-el-first  first flex_column_div'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ec57m2-026acd7342e95f830f647ada160fd05f\">\n#top .av-special-heading.av-ec57m2-026acd7342e95f830f647ada160fd05f{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-ec57m2-026acd7342e95f830f647ada160fd05f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-ec57m2-026acd7342e95f830f647ada160fd05f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-ec57m2-026acd7342e95f830f647ada160fd05f av-special-heading-h2  avia-builder-el-15  el_before_av_textblock  avia-builder-el-first'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Execution<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mg80aefv-cb12e9ce5c48306b95f60cf9a145c051\">\n#top .av_textblock_section.av-mg80aefv-cb12e9ce5c48306b95f60cf9a145c051 .avia_textblock{\nfont-size:16px;\n}\n<\/style>\n<section  class='av_textblock_section av-mg80aefv-cb12e9ce5c48306b95f60cf9a145c051'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li data-start=\"287\" data-end=\"370\">Vertical single-stage brass pumps with side channel impeller<\/li>\n<li data-start=\"287\" data-end=\"370\">Ideal for maintaining circulation pressure in open circuit systems<\/li>\n<li data-start=\"287\" data-end=\"370\">Operation with clear and clean media such as water or oil without suspended or abrasive particles<\/li>\n<li data-start=\"287\" data-end=\"370\">Versatile application possibilities, especially in the dual-frequency version available on request<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-c5rx96-f221b152f10a10de3d26909ba118f222\">\n.flex_column.av-c5rx96-f221b152f10a10de3d26909ba118f222{\npadding:0 20px 10px 20px;\n}\n<\/style>\n<div  class='flex_column av-c5rx96-f221b152f10a10de3d26909ba118f222 av_one_half  avia-builder-el-17  el_after_av_one_half  avia-builder-el-last  flex_column_div'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-a68wmy-8fca6e220ffd2b2a5cdc81a71076eed4\">\n#top .av-special-heading.av-a68wmy-8fca6e220ffd2b2a5cdc81a71076eed4{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-a68wmy-8fca6e220ffd2b2a5cdc81a71076eed4 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-a68wmy-8fca6e220ffd2b2a5cdc81a71076eed4 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-a68wmy-8fca6e220ffd2b2a5cdc81a71076eed4 av-special-heading-h2  avia-builder-el-18  el_before_av_textblock  avia-builder-el-first'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Applications<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mg80al2l-b32a00ef6247a44d3664d400573071a1\">\n#top .av_textblock_section.av-mg80al2l-b32a00ef6247a44d3664d400573071a1 .avia_textblock{\nfont-size:16px;\n}\n<\/style>\n<section  class='av_textblock_section av-mg80al2l-b32a00ef6247a44d3664d400573071a1'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li>Tempering<\/li>\n<li>Drying<\/li>\n<li>Typography and lithography<\/li>\n<li>Oil-hydraulic systems<\/li>\n<li>Cooling<\/li>\n<li>Medicine<\/li>\n<li>Chemical and pharmaceutical technology<\/li>\n<li>Steam sterilizers<\/li>\n<li>Osmosis and filter systems<\/li>\n<li>Robot and automation technology<\/li>\n<li>Water treatment<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-7590'><div class='entry-content-wrapper clearfix'><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6wvxve-da78bf7ba259ec671bbc605f58465a50\">\n.flex_column.av-6wvxve-da78bf7ba259ec671bbc605f58465a50{\npadding:0 20px 10px 20px;\n}\n<\/style>\n<div  class='flex_column av-6wvxve-da78bf7ba259ec671bbc605f58465a50 av_one_half  avia-builder-el-20  el_after_av_section  el_before_av_one_half  avia-builder-el-first  first flex_column_div'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5bieay-b1d56d3828f07b4d4717f29e161c6c8d\">\n#top .av-special-heading.av-5bieay-b1d56d3828f07b4d4717f29e161c6c8d{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-5bieay-b1d56d3828f07b4d4717f29e161c6c8d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-5bieay-b1d56d3828f07b4d4717f29e161c6c8d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-5bieay-b1d56d3828f07b4d4717f29e161c6c8d av-special-heading-h2  avia-builder-el-21  el_before_av_textblock  avia-builder-el-first'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Operating conditions<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mg80asd3-7e0a6e3029505b8faa41981afab80a5e\">\n#top .av_textblock_section.av-mg80asd3-7e0a6e3029505b8faa41981afab80a5e .avia_textblock{\nfont-size:16px;\n}\n<\/style>\n<section  class='av_textblock_section av-mg80asd3-7e0a6e3029505b8faa41981afab80a5e'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li>Temperature of the liquid (with appropriate antifreeze): -20 \u00b0C \/ +150\u00b0C.<\/li>\n<li>Operating limits at room temperature: -10\u00b0C\/+40\u00b0C.<\/li>\n<li>For clear water\/oil and non-aggressive solutions without abrasive substances<\/li>\n<li>Effizienzklasse IE3 f\u00fcr Drehstrommotoren >0,75 kW<\/li>\n<li>Continuous operation S1<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4rv3ca-523737635730274b8d58d6f044d8bdeb\">\n.flex_column.av-4rv3ca-523737635730274b8d58d6f044d8bdeb{\npadding:0 20px 10px 20px;\n}\n<\/style>\n<div  class='flex_column av-4rv3ca-523737635730274b8d58d6f044d8bdeb av_one_half  avia-builder-el-23  el_after_av_one_half  el_before_av_hr  flex_column_div'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2greq2-ca666df4c59bcc22960dda6d56243be1\">\n#top .av-special-heading.av-2greq2-ca666df4c59bcc22960dda6d56243be1{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-2greq2-ca666df4c59bcc22960dda6d56243be1 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2greq2-ca666df4c59bcc22960dda6d56243be1 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2greq2-ca666df4c59bcc22960dda6d56243be1 av-special-heading-h2  avia-builder-el-24  el_before_av_textblock  avia-builder-el-first'><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Special versions (on request)<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mg80azrz-351198886bd84eecd3dd14ea3fa2d809\">\n#top .av_textblock_section.av-mg80azrz-351198886bd84eecd3dd14ea3fa2d809 .avia_textblock{\nfont-size:16px;\n}\n<\/style>\n<section  class='av_textblock_section av-mg80azrz-351198886bd84eecd3dd14ea3fa2d809'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li>Deviating voltages<\/li>\n<li>Operation at 60 Hz<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<div  class='hr av-245ffz-024df430b43ecd4f720bad9e6e3caff0 hr-default  avia-builder-el-26  el_after_av_one_half  el_before_av_section  avia-builder-el-last'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-97cvg1-d83f100017d2b66dfac2e7b80b960aee\">\n.avia-section.av-97cvg1-d83f100017d2b66dfac2e7b80b960aee{\nbackground-color:#0069b4;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-97cvg1-d83f100017d2b66dfac2e7b80b960aee alternate_color avia-section-large avia-no-border-styling  avia-builder-el-27  el_after_av_hr  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-7590'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-700fnl-667eda7a6a65e21daca0974962418576\">\n#top .av_textblock_section.av-700fnl-667eda7a6a65e21daca0974962418576 .avia_textblock{\nfont-size:30px;\ncolor:#ffffff;\ntext-align:center;\n}\n<\/style>\n<section  class='av_textblock_section av-700fnl-667eda7a6a65e21daca0974962418576'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p class=\"vc_custom_heading\"><strong>Do you still have questions or need support?<\/strong><\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5m861t-83254134adfbd4d75d679b148334907a\">\n#top .av_textblock_section.av-5m861t-83254134adfbd4d75d679b148334907a .avia_textblock{\nfont-size:16px;\ncolor:#ffffff;\ntext-align:center;\n}\n<\/style>\n<section  class='av_textblock_section av-5m861t-83254134adfbd4d75d679b148334907a'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>Contact us and let us work together to find the best solution for your requirements.<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-461ivl-4ff2acef6369653212c3dc336e537645\">\n#top .hr.hr-invisible.av-461ivl-4ff2acef6369653212c3dc336e537645{\nheight:10px;\n}\n<\/style>\n<div  class='hr av-461ivl-4ff2acef6369653212c3dc336e537645 hr-invisible  avia-builder-el-30  el_after_av_textblock  el_before_av_button'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  class='avia-button-wrap av-220on5-16e944e0aa57557524596ac79d409d3a-wrap avia-button-center  avia-builder-el-31  el_after_av_hr  avia-builder-el-last'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-220on5-16e944e0aa57557524596ac79d409d3a\">\n#top #wrap_all .avia-button.av-220on5-16e944e0aa57557524596ac79d409d3a{\nfont-size:20px;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-220on5-16e944e0aa57557524596ac79d409d3a:hover{\ncolor:white;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-220on5-16e944e0aa57557524596ac79d409d3a:hover .avia-svg-icon svg:first-child{\nfill:white;\nstroke:white;\n}\n<\/style>\n<a href='https:\/\/linn-pumpen.de\/en\/kontakt\/'  class='avia-button av-220on5-16e944e0aa57557524596ac79d409d3a av-link-btn avia-icon_select-no avia-size-large avia-position-center avia-color-light avia-font-color-theme-color-highlight'  title=\"Learn more\" aria-label=\"Learn more\"><span class='avia_iconbox_title' >Get in touch with us<\/span><span class='avia_button_background avia-button avia-color-theme-color-highlight' ><\/span><\/a><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-lz9jb0h9-e8f2e95147dbedc499b62554f268e590 alternate_color avia-section-default avia-shadow  avia-builder-el-32  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-7590'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-21729-83b3e725b6b7d105df94aa43c7a2be32'   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h4 style=\"text-align: center;\">Further products<\/h4>\n<\/div><\/section>\n<div  class='hr av-4y8tsx-59bbac460be2069df252db70568ed3ce hr-short  avia-builder-el-34  el_after_av_textblock  el_before_av_portfolio  avia-builder-el-last  hr-center'><span class='hr-inner'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div  id=\"av-sc-portfolio-1\"  class='grid-sort-container isotope   no_margin-container with-title-container grid-total-even grid-col-4 grid-links-' data-portfolio-id='1'><div data-ajax-id='7590' class='grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-7590 grid-entry-overview grid-loop-1 grid-parity-odd  eintauchpumpen_sort  av_one_fourth first default_av_fullwidth'><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/linn-pumpen.de\/en\/produkt\/ap-2\/\" title='VP'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"238\" height=\"300\" src=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-238x300.png\" class=\"wp-image-7565 avia-img-lazy-loading-not-7565 attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-238x300.png 238w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-768x967.png 768w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-10x12.png 10w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1-560x705.png 560w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png 813w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: VP\"><h3 class='grid-entry-title entry-title'  itemprop=\"headline\" ><a href='https:\/\/linn-pumpen.de\/en\/produkt\/ap-2\/' title='VP'>VP<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='7587' class='grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-7587 grid-entry-overview grid-loop-2 grid-parity-even  eintauchpumpen_sort  av_one_fourth  default_av_fullwidth'><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/linn-pumpen.de\/en\/produkt\/ap\/\" title='AP'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" loading=\"lazy\" width=\"210\" height=\"300\" src=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/AP100-112_geschlossen_web-718x1024-1-210x300.jpg\" class=\"wp-image-7563 avia-img-lazy-loading-7563 attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/AP100-112_geschlossen_web-718x1024-1-210x300.jpg 210w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/AP100-112_geschlossen_web-718x1024-1-8x12.jpg 8w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/AP100-112_geschlossen_web-718x1024-1-494x705.jpg 494w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/AP100-112_geschlossen_web-718x1024-1.jpg 718w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: AP\"><h3 class='grid-entry-title entry-title'  itemprop=\"headline\" ><a href='https:\/\/linn-pumpen.de\/en\/produkt\/ap\/' title='AP'>AP<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='7583' class='grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-7583 grid-entry-overview grid-loop-3 grid-parity-odd  eintauchpumpen_sort  av_one_fourth  default_av_fullwidth'><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/linn-pumpen.de\/en\/produkt\/epc\/\" title='EPC'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" loading=\"lazy\" width=\"221\" height=\"300\" src=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-221x300.jpg\" class=\"wp-image-7564 avia-img-lazy-loading-7564 attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-221x300.jpg 221w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-758x1030.jpg 758w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-768x1043.jpg 768w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-1131x1536.jpg 1131w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-9x12.jpg 9w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-1104x1500.jpg 1104w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web-519x705.jpg 519w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/EPC80-90_web.jpg 1178w\" sizes=\"auto, (max-width: 221px) 100vw, 221px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: EPC\"><h3 class='grid-entry-title entry-title'  itemprop=\"headline\" ><a href='https:\/\/linn-pumpen.de\/en\/produkt\/epc\/' title='EPC'>EPC<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='7578' class='grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-7578 grid-entry-overview grid-loop-4 grid-parity-even  post-entry-last  eintauchpumpen_sort  av_one_fourth  default_av_fullwidth'><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/linn-pumpen.de\/en\/produkt\/imm\/\" title='IMM'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" loading=\"lazy\" width=\"206\" height=\"300\" src=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-206x300.jpg\" class=\"wp-image-7561 avia-img-lazy-loading-7561 attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-206x300.jpg 206w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-706x1030.jpg 706w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-768x1121.jpg 768w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-1052x1536.jpg 1052w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-8x12.jpg 8w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-1028x1500.jpg 1028w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web-483x705.jpg 483w, https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/IMM80_web.jpg 1214w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: IMM\"><h3 class='grid-entry-title entry-title'  itemprop=\"headline\" ><a href='https:\/\/linn-pumpen.de\/en\/produkt\/imm\/' title='IMM'>IMM<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_3'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-7590'><div class='entry-content-wrapper clearfix'>","protected":false},"excerpt":{"rendered":"<p>Eintauchpumpe VP<\/p>","protected":false},"author":1,"featured_media":7565,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[43],"class_list":["post-7590","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-eintauchpumpen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>VP Vertikale Eintauchpumpen mit Peripheralrad | Linn-Pumpen<\/title>\n<meta name=\"description\" content=\"Vertikale, dichtungslose Eintauchpumpe mit Peripheralrad in Blockbauweise, ideal zur Umw\u00e4lzdruckhaltung in o\u001dffenen Kreislaufsystemen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linn-pumpen.de\/en\/product\/ap-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VP\" \/>\n<meta property=\"og:description\" content=\"Vertikale, dichtungslose Eintauchpumpe mit Peripheralrad in Blockbauweise, ideal zur Umw\u00e4lzdruckhaltung in o\u001dffenen Kreislaufsystemen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linn-pumpen.de\/en\/product\/ap-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Linn-Pumpen GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T09:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"813\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/\",\"url\":\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/\",\"name\":\"VP Vertikale Eintauchpumpen mit Peripheralrad | Linn-Pumpen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linn-pumpen.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/VP440-813x1024-1.png\",\"datePublished\":\"2025-10-18T07:28:10+00:00\",\"dateModified\":\"2025-11-20T09:27:38+00:00\",\"description\":\"Vertikale, dichtungslose Eintauchpumpe mit Peripheralrad in Blockbauweise, ideal zur Umw\u00e4lzdruckhaltung in o\\u001dffenen Kreislaufsystemen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linn-pumpen.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/VP440-813x1024-1.png\",\"contentUrl\":\"https:\\\/\\\/linn-pumpen.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/VP440-813x1024-1.png\",\"width\":813,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/produkt\\\/ap-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/linn-pumpen.de\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/#website\",\"url\":\"https:\\\/\\\/linn-pumpen.de\\\/\",\"name\":\"Linn-Pumpen\",\"description\":\"Ihr Partner f&uuml;r hochwertige Zahnradpumpen\",\"publisher\":{\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linn-pumpen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/#organization\",\"name\":\"Linn-Pumpen GmbH\",\"url\":\"https:\\\/\\\/linn-pumpen.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linn-pumpen.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Logo_LINNPumpen_512x512.png\",\"contentUrl\":\"https:\\\/\\\/linn-pumpen.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Logo_LINNPumpen_512x512.png\",\"width\":500,\"height\":500,\"caption\":\"Linn-Pumpen GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/linn-pumpen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VP Vertical immersion pumps with peripheral impeller | Linn pumps","description":"Vertical, sealless submersible pump with peripheral impeller in close-coupled design, ideal for maintaining circulation pressure in open circuit systems.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linn-pumpen.de\/en\/product\/ap-2\/","og_locale":"en_US","og_type":"article","og_title":"VP","og_description":"Vertikale, dichtungslose Eintauchpumpe mit Peripheralrad in Blockbauweise, ideal zur Umw\u00e4lzdruckhaltung in o\u001dffenen Kreislaufsystemen.","og_url":"https:\/\/linn-pumpen.de\/en\/product\/ap-2\/","og_site_name":"Linn-Pumpen GmbH","article_modified_time":"2025-11-20T09:27:38+00:00","og_image":[{"width":813,"height":1024,"url":"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/linn-pumpen.de\/produkt\/ap-2\/","url":"https:\/\/linn-pumpen.de\/produkt\/ap-2\/","name":"VP Vertical immersion pumps with peripheral impeller | Linn pumps","isPartOf":{"@id":"https:\/\/linn-pumpen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/linn-pumpen.de\/produkt\/ap-2\/#primaryimage"},"image":{"@id":"https:\/\/linn-pumpen.de\/produkt\/ap-2\/#primaryimage"},"thumbnailUrl":"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png","datePublished":"2025-10-18T07:28:10+00:00","dateModified":"2025-11-20T09:27:38+00:00","description":"Vertical, sealless submersible pump with peripheral impeller in close-coupled design, ideal for maintaining circulation pressure in open circuit systems.","breadcrumb":{"@id":"https:\/\/linn-pumpen.de\/produkt\/ap-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linn-pumpen.de\/produkt\/ap-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/linn-pumpen.de\/produkt\/ap-2\/#primaryimage","url":"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png","contentUrl":"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/10\/VP440-813x1024-1.png","width":813,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/linn-pumpen.de\/produkt\/ap-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/linn-pumpen.de\/homepage\/"},{"@type":"ListItem","position":2,"name":"VP"}]},{"@type":"WebSite","@id":"https:\/\/linn-pumpen.de\/#website","url":"https:\/\/linn-pumpen.de\/","name":"Linn pumps","description":"Ihr Partner f&uuml;r hochwertige Zahnradpumpen","publisher":{"@id":"https:\/\/linn-pumpen.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linn-pumpen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/linn-pumpen.de\/#organization","name":"Linn-Pumpen GmbH","url":"https:\/\/linn-pumpen.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/linn-pumpen.de\/#\/schema\/logo\/image\/","url":"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/11\/Logo_LINNPumpen_512x512.png","contentUrl":"https:\/\/linn-pumpen.de\/wp-content\/uploads\/2025\/11\/Logo_LINNPumpen_512x512.png","width":500,"height":500,"caption":"Linn-Pumpen GmbH"},"image":{"@id":"https:\/\/linn-pumpen.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/portfolio\/7590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/comments?post=7590"}],"version-history":[{"count":4,"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/portfolio\/7590\/revisions"}],"predecessor-version":[{"id":8569,"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/portfolio\/7590\/revisions\/8569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/media\/7565"}],"wp:attachment":[{"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/media?parent=7590"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/tags?post=7590"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/linn-pumpen.de\/en\/wp-json\/wp\/v2\/portfolio_entries?post=7590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}